{"id":20281,"date":"2025-08-21T05:17:39","date_gmt":"2025-08-21T12:17:39","guid":{"rendered":"https:\/\/www.netgear.com\/hub\/?post_type=tribe_events&#038;p=20281"},"modified":"2025-11-11T13:19:24","modified_gmt":"2025-11-11T21:19:24","slug":"s14-solutions-day-2025-stuttgart-av","status":"publish","type":"tribe_events","link":"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/","title":{"rendered":"S14 Exertis AV Solutions Day"},"content":{"rendered":"<div class=\"StyleWrapper_wrapper \">\n<div class=\"fr-view HtmlBlock_html\">\n<h1 id=\"h1_n\">S14 Solutions Day 2025<\/h1>\n<h2>Das Branchen-Highlight von Exertis AV \u2013 live in Stuttgart<\/h2>\n<\/div>\n<\/div>\n<div class=\"StyleWrapper_wrapper \">\n<div class=\"fr-view HtmlBlock_html\">\n<div data-is-processed-by-editor=\"true\"><strong>Come to where the AVolutions starts<\/strong><br \/>\n<strong>\u00a0<\/strong><br \/>\nDer S14 Solutions Day ist zur\u00fcck \u2013 erstmalig in der einzigartigen Atmosph\u00e4re der Phoenixhalle im R\u00f6merkastell in Stuttgart pr\u00e4sentieren wir Ihnen die neuesten L\u00f6sungen, Technologien und Innovationen aus der Welt der AV-Medientechnik.Tauchen Sie ein in f\u00fcnf erlebnisreiche Themenwelten:<\/div>\n<\/div>\n<\/div>\n<div class=\"StyleWrapper_wrapper \">\n<div>\n<p><span class=\"lazy-load-image-background opacity lazy-load-image-loaded\"><img decoding=\"async\" src=\"https:\/\/www.exertisproav.de\/images\/24\/root_neu\/images\/homepage\/icon_checkmark_3.png\" sizes=\"24px\" srcset=\"\/images\/24\/root_neu\/images\/homepage\/icon_checkmark_3.png 24w\" alt=\"\" \/><\/span><\/p>\n<div><strong>Digital Signage<\/strong><\/div>\n<\/div>\n<div>\n<p><span class=\"lazy-load-image-background opacity lazy-load-image-loaded\"><img decoding=\"async\" src=\"https:\/\/www.exertisproav.de\/images\/24\/root_neu\/images\/homepage\/icon_checkmark_3.png\" sizes=\"24px\" srcset=\"\/images\/24\/root_neu\/images\/homepage\/icon_checkmark_3.png 24w\" alt=\"\" \/><\/span><\/p>\n<div><strong>UCC &amp; Professional Audio<\/strong><\/div>\n<\/div>\n<div>\n<p><span class=\"lazy-load-image-background opacity lazy-load-image-loaded\"><img decoding=\"async\" src=\"https:\/\/www.exertisproav.de\/images\/24\/root_neu\/images\/homepage\/icon_checkmark_3.png\" sizes=\"24px\" srcset=\"\/images\/24\/root_neu\/images\/homepage\/icon_checkmark_3.png 24w\" alt=\"\" \/><\/span><\/p>\n<div><strong>LED \/ Displays<\/strong><\/div>\n<\/div>\n<div>\n<p><span class=\"lazy-load-image-background opacity lazy-load-image-loaded\"><img decoding=\"async\" src=\"https:\/\/www.exertisproav.de\/images\/24\/root_neu\/images\/homepage\/icon_checkmark_3.png\" sizes=\"24px\" srcset=\"\/images\/24\/root_neu\/images\/homepage\/icon_checkmark_3.png 24w\" alt=\"\" \/><\/span><\/p>\n<div><strong>Signalmanagement<\/strong><\/div>\n<\/div>\n<div>\n<p><span class=\"lazy-load-image-background opacity lazy-load-image-loaded\"><img decoding=\"async\" src=\"https:\/\/www.exertisproav.de\/images\/24\/root_neu\/images\/homepage\/icon_checkmark_3.png\" sizes=\"24px\" srcset=\"\/images\/24\/root_neu\/images\/homepage\/icon_checkmark_3.png 24w\" alt=\"\" \/><\/span><\/p>\n<div><strong>Essentials<\/strong><\/div>\n<\/div>\n<\/div>\n<div class=\"StyleWrapper_wrapper \">\n<div class=\"fr-view HtmlBlock_html\">\n<div data-is-processed-by-editor=\"true\">\ud83d\uddd3\ufe0f\u00a0<strong data-start=\"782\" data-end=\"792\">Datum:<\/strong>\u00a024. September 2025<br data-start=\"811\" data-end=\"814\" \/>\ud83d\udccd\u00a0<strong data-start=\"817\" data-end=\"825\">Ort:<\/strong>\u00a0Phoenixhalle im R\u00f6merkastell, Stuttgart-Bad Cannstatt<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der S14 Solutions Day 2025 von Exertis AV ist das Branchen-Highlight f\u00fcr AV-Medientechnik. Am 24. September in der Phoenixhalle im R\u00f6merkastell Stuttgart erwarten Sie neueste Technologien, spannende Innovationen und f\u00fcnf Themenwelten: Digital Signage, UCC &#038; Professional Audio, LED\/Displays, Signalmanagement und Essentials.<\/p>\n","protected":false},"author":94,"featured_media":20282,"template":"","meta":{"_acf_changed":false,"content-type":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[794,726,834,743],"tribe_events_cat":[735],"class_list":["post-20281","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-germany","tag-proav","tag-stuttgart","tag-trade-show","tribe_events_cat-local-partner-events","cat_local-partner-events"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S14 Exertis AV Solutions Day - NETGEAR Blog<\/title>\n<meta name=\"description\" content=\"S14 Solutions Day 2025 in Stuttgart: Erleben Sie am 24. Sept. neueste AV-Technologien, Trends &amp; Networking live in der Phoenixhalle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S14 Exertis AV Solutions Day - NETGEAR Blog\" \/>\n<meta property=\"og:description\" content=\"S14 Solutions Day 2025 in Stuttgart: Erleben Sie am 24. Sept. neueste AV-Technologien, Trends &amp; Networking live in der Phoenixhalle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/\" \/>\n<meta property=\"og:site_name\" content=\"NETGEAR Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NetgearAU\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T21:19:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netgear.com\/hub\/wp-content\/uploads\/2025\/08\/S14-Exertis-AV-Solutions-Day.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1919\" \/>\n\t<meta property=\"og:image:height\" content=\"740\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NETGEAR\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/event\\\/s14-solutions-day-2025-stuttgart-av\\\/\",\"url\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/event\\\/s14-solutions-day-2025-stuttgart-av\\\/\",\"name\":\"S14 Exertis AV Solutions Day - NETGEAR Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/event\\\/s14-solutions-day-2025-stuttgart-av\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/event\\\/s14-solutions-day-2025-stuttgart-av\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/S14-Exertis-AV-Solutions-Day.webp\",\"datePublished\":\"2025-08-21T12:17:39+00:00\",\"dateModified\":\"2025-11-11T21:19:24+00:00\",\"description\":\"S14 Solutions Day 2025 in Stuttgart: Erleben Sie am 24. Sept. neueste AV-Technologien, Trends & Networking live in der Phoenixhalle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/event\\\/s14-solutions-day-2025-stuttgart-av\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.netgear.com\\\/hub\\\/event\\\/s14-solutions-day-2025-stuttgart-av\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/event\\\/s14-solutions-day-2025-stuttgart-av\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/S14-Exertis-AV-Solutions-Day.webp\",\"contentUrl\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/S14-Exertis-AV-Solutions-Day.webp\",\"width\":1919,\"height\":740},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/event\\\/s14-solutions-day-2025-stuttgart-av\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/business\\\/calendar\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S14 Exertis AV Solutions Day\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/#website\",\"url\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/\",\"name\":\"NETGEAR\",\"description\":\"Learn about NETGEAR Products and services\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/#organization\",\"name\":\"NETGEAR\",\"url\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"NETGEAR\"},\"image\":{\"@id\":\"https:\\\/\\\/www.netgear.com\\\/hub\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NetgearAU\\\/\",\"https:\\\/\\\/x.com\\\/NETGEAR\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/netgear\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S14 Exertis AV Solutions Day - NETGEAR Blog","description":"S14 Solutions Day 2025 in Stuttgart: Erleben Sie am 24. Sept. neueste AV-Technologien, Trends & Networking live in der Phoenixhalle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/","og_locale":"en_US","og_type":"article","og_title":"S14 Exertis AV Solutions Day - NETGEAR Blog","og_description":"S14 Solutions Day 2025 in Stuttgart: Erleben Sie am 24. Sept. neueste AV-Technologien, Trends & Networking live in der Phoenixhalle.","og_url":"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/","og_site_name":"NETGEAR Blog","article_publisher":"https:\/\/www.facebook.com\/NetgearAU\/","article_modified_time":"2025-11-11T21:19:24+00:00","og_image":[{"width":1919,"height":740,"url":"https:\/\/www.netgear.com\/hub\/wp-content\/uploads\/2025\/08\/S14-Exertis-AV-Solutions-Day.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@NETGEAR","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/","url":"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/","name":"S14 Exertis AV Solutions Day - NETGEAR Blog","isPartOf":{"@id":"https:\/\/www.netgear.com\/hub\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/#primaryimage"},"image":{"@id":"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netgear.com\/hub\/wp-content\/uploads\/2025\/08\/S14-Exertis-AV-Solutions-Day.webp","datePublished":"2025-08-21T12:17:39+00:00","dateModified":"2025-11-11T21:19:24+00:00","description":"S14 Solutions Day 2025 in Stuttgart: Erleben Sie am 24. Sept. neueste AV-Technologien, Trends & Networking live in der Phoenixhalle.","breadcrumb":{"@id":"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/#primaryimage","url":"https:\/\/www.netgear.com\/hub\/wp-content\/uploads\/2025\/08\/S14-Exertis-AV-Solutions-Day.webp","contentUrl":"https:\/\/www.netgear.com\/hub\/wp-content\/uploads\/2025\/08\/S14-Exertis-AV-Solutions-Day.webp","width":1919,"height":740},{"@type":"BreadcrumbList","@id":"https:\/\/www.netgear.com\/hub\/event\/s14-solutions-day-2025-stuttgart-av\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.netgear.com\/hub\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.netgear.com\/hub\/business\/calendar\/"},{"@type":"ListItem","position":3,"name":"S14 Exertis AV Solutions Day"}]},{"@type":"WebSite","@id":"https:\/\/www.netgear.com\/hub\/#website","url":"https:\/\/www.netgear.com\/hub\/","name":"NETGEAR","description":"Learn about NETGEAR Products and services","publisher":{"@id":"https:\/\/www.netgear.com\/hub\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netgear.com\/hub\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.netgear.com\/hub\/#organization","name":"NETGEAR","url":"https:\/\/www.netgear.com\/hub\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.netgear.com\/hub\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"NETGEAR"},"image":{"@id":"https:\/\/www.netgear.com\/hub\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NetgearAU\/","https:\/\/x.com\/NETGEAR","https:\/\/www.linkedin.com\/company\/netgear"]}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.netgear.com\/hub\/wp-json\/wp\/v2\/tribe_events\/20281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netgear.com\/hub\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.netgear.com\/hub\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.netgear.com\/hub\/wp-json\/wp\/v2\/users\/94"}],"version-history":[{"count":5,"href":"https:\/\/www.netgear.com\/hub\/wp-json\/wp\/v2\/tribe_events\/20281\/revisions"}],"predecessor-version":[{"id":21831,"href":"https:\/\/www.netgear.com\/hub\/wp-json\/wp\/v2\/tribe_events\/20281\/revisions\/21831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.netgear.com\/hub\/wp-json\/wp\/v2\/media\/20282"}],"wp:attachment":[{"href":"https:\/\/www.netgear.com\/hub\/wp-json\/wp\/v2\/media?parent=20281"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netgear.com\/hub\/wp-json\/wp\/v2\/tags?post=20281"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.netgear.com\/hub\/wp-json\/wp\/v2\/tribe_events_cat?post=20281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}