{"id":10922,"date":"2025-10-15T10:38:09","date_gmt":"2025-10-16T08:38:51","guid":{"rendered":"https:\/\/dehub.netgear.com\/de\/hub\/?page_id=10922"},"modified":"2025-11-25T17:00:20","modified_gmt":"2025-11-25T16:00:20","slug":"higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth","status":"publish","type":"page","link":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/","title":{"rendered":"Higashi Holdings entscheidet sich f\u00fcr NETGEAR"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignone size-full wp-image-10681\" style=\"border-radius: 1em;\" src=\"https:\/\/www.netgear.com\/hub\/wp-content\/uploads\/2025\/09\/DSC03641-scaled.jpg\" alt=\"\" width=\"1048\" height=\"511\" \/><\/p>\n    <div class=\"table-of-content bg-gray\">\n        <p><strong>IN THIS ARTICLE<\/strong><\/p>\n        <ul>\n                        <li><a href=\"#topic1\">Zusammenfassung<\/a><\/li>\n                        <li><a href=\"#topic2\">Hintergrund<\/a><\/li>\n                        <li><a href=\"#topic3\">Herausforderung<\/a><\/li>\n                        <li><a href=\"#topic4\">L\u00f6sung<\/a><\/li>\n                        <li><a href=\"#topic5\">Ergebnisse<\/a><\/li>\n                        <li><a href=\"#topic6\">Fazit<\/a><\/li>\n                        <li><a href=\"#topic7\">Mehr Informationen<\/a><\/li>\n                    <\/ul>\n    <\/div>\n        <div id=\"topic1\" class=\"skip-item\">\n                        <h2>Zusammenfassung<\/h2>\n                <div style=\"background-color: #eeeeee;padding: 20px;width: 33%;float: right\">\n<p><strong>Name:<\/strong><br \/>\nHigashi Holdings Co., Ltd<\/p>\n<p><strong>Branche:<\/strong><br \/>\nIntegrierte Fracht &amp; Logistik<\/p>\n<p><strong>Webseite:<\/strong><br \/>\n<a href=\"http:\/\/www.e-higashi.co.jp\">e-higashi.co.jp<\/a><\/p>\n<p><strong>Standort:<\/strong><br \/>\nOsaka, Japan<\/p>\n<\/div>\n<p>Wie viele andere Unternehmen ist Higashi Holdings auf eine zuverl\u00e4ssige und skalierbare IT- und Netzwerkinfrastruktur angewiesen, um die Gesch\u00e4ftskontinuit\u00e4t und das Wachstum zu sichern. Als der bisherige Technologieanbieter aufgrund von Lieferschwierigkeiten nicht mehr in der Lage war, den wachsenden Anforderungen gerecht zu werden, wandte sich das Logistikunternehmen an NETGEAR Enterprise.<\/p>\n<p>NETGEAR konnte nicht nur in Bezug auf Leistung, Zuverl\u00e4ssigkeit und Qualit\u00e4t mit dem vorherigen Anbieter mithalten, sondern \u00fcberzeugte auch durch attraktive Preise und die fristgerechte Lieferung von Wireless Access Points und Multi-Gigabit-Switches. Ein weiterer Vorteil: NETGEAR Insight Cloud erm\u00f6glicht es dem IT-Team von Higashi Holdings, das Netzwerk einfach und auch remote zu verwalten, was die Arbeitsbelastung deutlich reduziert.<\/p>\n<p>Dank der NETGEAR-L\u00f6sung kann Higashi Holdings sicher sein, dass die unterbrechungsfreie Gesch\u00e4ftskontinuit\u00e4t und das k\u00fcnftige Wachstum optimal unterst\u00fctzt werden.<\/p>\n    <\/div>\n        <div id=\"topic2\" class=\"skip-item\">\n                        <h2>Hintergrund<\/h2>\n                <p>Mit Hauptsitz in Osaka und \u00fcber <strong data-start=\"548\" data-end=\"571\">80 Jahren Erfahrung<\/strong> bietet <strong data-start=\"579\" data-end=\"608\">Higashi Holdings Co., Ltd<\/strong> japanischen Gesch\u00e4ftskunden ein breites Spektrum an <strong data-start=\"661\" data-end=\"685\">B2B-Dienstleistungen<\/strong>. Das Unternehmen ist aus den Bereichen Logistik und Lagerhaltung hervorgegangen und hat sein Leistungsportfolio im Laufe der Jahre um Dienstleistungen wie <strong data-start=\"841\" data-end=\"908\">B\u00fcroumz\u00fcge, innerbetriebliche Lieferungen, Third-Party-Logistik<\/strong> und sogar <strong data-start=\"919\" data-end=\"938\">Pflege-Services<\/strong> erweitert.<\/p>\n    <\/div>\n        <div id=\"topic3\" class=\"skip-item\">\n                        <h2>Herausforderung<\/h2>\n                <p data-start=\"983\" data-end=\"1262\">Eine <strong data-start=\"988\" data-end=\"1050\">zuverl\u00e4ssige und skalierbare IT- und Netzwerkinfrastruktur<\/strong> ist seit jeher entscheidend f\u00fcr Higashi Holdings. Besonders im Logistiksektor f\u00fchren Ausfallzeiten nicht nur zu <strong data-start=\"1163\" data-end=\"1199\">betriebsinternen Unterbrechungen<\/strong>, sondern k\u00f6nnen auch das <strong data-start=\"1225\" data-end=\"1249\">Vertrauen der Kunden<\/strong> gef\u00e4hrden.<\/p>\n<p data-start=\"1264\" data-end=\"1438\">Mit dem <strong data-start=\"1272\" data-end=\"1301\">Wachstum des Unternehmens<\/strong> \u2013 sowohl hinsichtlich der Gesch\u00e4ftsbereiche als auch der Standorte \u2013 stieg auch der Bedarf an einer leistungsf\u00e4higeren Netzwerkumgebung.<\/p>\n<p data-start=\"1440\" data-end=\"1692\">Das Problem: Der bisherige Technologieanbieter war von der <strong data-start=\"1499\" data-end=\"1531\">globalen Halbleiterknappheit<\/strong> betroffen, was zu <strong data-start=\"1550\" data-end=\"1591\">Lieferzeiten von bis zu sechs Monaten<\/strong> f\u00fchrte. Gleichzeitig stiegen die <strong data-start=\"1625\" data-end=\"1651\">Kosten f\u00fcr neue Ger\u00e4te<\/strong>, was das IT-Budget zus\u00e4tzlich belastete.<\/p>\n<p data-start=\"1694\" data-end=\"2040\">Das IT-Team ben\u00f6tigte daher <strong data-start=\"1722\" data-end=\"1767\">dringend eine leistungsf\u00e4hige Alternative<\/strong>, die <strong data-start=\"1773\" data-end=\"1794\">schnell verf\u00fcgbar<\/strong>, <strong data-start=\"1796\" data-end=\"1820\">preislich angemessen<\/strong> und <strong data-start=\"1825\" data-end=\"1843\">zukunftssicher<\/strong> war \u2013 ohne Kompromisse bei der Unternehmensleistung. Au\u00dferdem sollte die neue L\u00f6sung die <strong data-start=\"1933\" data-end=\"1991\">Netzwerkverwaltung an mehreren Standorten vereinfachen<\/strong> und das Unternehmen langfristig flexibel halten.<\/p>\n    <\/div>\n        <div id=\"topic4\" class=\"skip-item\">\n                        <h2>L\u00f6sung<\/h2>\n                <p data-start=\"2065\" data-end=\"2266\">Trotz des Zeitdrucks hat Higashi Holdings eine sorgf\u00e4ltige Evaluierung verschiedener Anbieter durchgef\u00fchrt und sich letztlich f\u00fcr <strong data-start=\"2195\" data-end=\"2217\">NETGEAR Enterprise<\/strong> entschieden. Die Gr\u00fcnde daf\u00fcr waren \u00fcberzeugend:<\/p>\n<ul data-start=\"2268\" data-end=\"2839\">\n<li data-start=\"2268\" data-end=\"2449\">\n<p data-start=\"2270\" data-end=\"2449\"><strong data-start=\"2270\" data-end=\"2282\">Leistung<\/strong>: Die NETGEAR-Ger\u00e4te boten dieselbe <strong data-start=\"2318\" data-end=\"2350\">Zuverl\u00e4ssigkeit und Qualit\u00e4t<\/strong> wie die Produkte des bisherigen Anbieters und unterst\u00fctzten reibungslose Abl\u00e4ufe im Tagesgesch\u00e4ft.<\/p>\n<\/li>\n<li data-start=\"2450\" data-end=\"2642\">\n<p data-start=\"2452\" data-end=\"2642\"><strong data-start=\"2452\" data-end=\"2500\">Verf\u00fcgbarkeit und Preis-Leistungs-Verh\u00e4ltnis<\/strong>: NETGEAR konnte die ben\u00f6tigte Hardware \u2013 <strong data-start=\"2542\" data-end=\"2591\">WLAN Access Points und Multi-Gigabit-Switches<\/strong> \u2013 <strong data-start=\"2594\" data-end=\"2633\">termingerecht und zu fairen Preisen<\/strong> liefern.<\/p>\n<\/li>\n<li data-start=\"2643\" data-end=\"2839\">\n<p data-start=\"2645\" data-end=\"2839\"><strong data-start=\"2645\" data-end=\"2668\">Zentrale Verwaltung<\/strong>: Mit <strong data-start=\"2674\" data-end=\"2699\">NETGEAR Insight Cloud<\/strong> konnte das gesamte Netzwerk \u00fcber mehrere Standorte hinweg <strong data-start=\"2758\" data-end=\"2790\">zentral und remote verwaltet<\/strong> werden, was die Komplexit\u00e4t deutlich reduzierte.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2841\" data-end=\"3245\">Die Umstellung erfolgte <strong data-start=\"2865\" data-end=\"2880\">phasenweise<\/strong>:<br data-start=\"2881\" data-end=\"2884\" \/>Zun\u00e4chst wurde ein <strong data-start=\"2903\" data-end=\"2919\">Pilotprojekt<\/strong> am Hauptsitz durchgef\u00fchrt, bei dem ein <strong data-start=\"2959\" data-end=\"2982\">WAX610 Access Point<\/strong> und ein <strong data-start=\"2991\" data-end=\"3031\">MS510TXUP Multi-Gigabit Smart Switch<\/strong> zum Einsatz kamen. Nach erfolgreicher Validierung wurde die L\u00f6sung schrittweise auf kleinere Lagerh\u00e4user ausgeweitet und schlie\u00dflich im <strong data-start=\"3168\" data-end=\"3194\">gro\u00dfen Logistikzentrum<\/strong>, das 2022 gebaut wurde, vollst\u00e4ndig implementiert.<\/p>\n    <\/div>\n        <div id=\"topic5\" class=\"skip-item\">\n                        <h2>Ergebnisse<\/h2>\n                <p data-start=\"3273\" data-end=\"3390\">Laut <strong data-start=\"3278\" data-end=\"3303\">Herrn Yuichiro Takada<\/strong>, stellvertretender Leiter der Abteilung IT-Planung &amp; Entwicklung bei Higashi Holdings:<\/p>\n<blockquote data-start=\"3392\" data-end=\"3558\">\n<p data-start=\"3394\" data-end=\"3558\">\u201eDie NETGEAR-Produkte bieten <strong data-start=\"3423\" data-end=\"3446\">Enterprise-Leistung<\/strong>, die mit unseren bisherigen Ger\u00e4ten <strong data-start=\"3483\" data-end=\"3506\">voll mithalten kann<\/strong> \u2013 ohne Einbu\u00dfen bei Qualit\u00e4t oder Zuverl\u00e4ssigkeit.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"3560\" data-end=\"3571\">Er erg\u00e4nzt:<\/p>\n<blockquote data-start=\"3573\" data-end=\"3792\">\n<p data-start=\"3575\" data-end=\"3792\">\u201eDurch die zentrale Verwaltung \u00fcber <strong data-start=\"3611\" data-end=\"3630\">NETGEAR Insight<\/strong> konnten wir die IT-Komplexit\u00e4t erheblich reduzieren, t\u00e4gliche Aufgaben vereinfachen und unser Team f\u00fchlt sich sicherer in der <strong data-start=\"3757\" data-end=\"3790\">Verwaltung mehrerer Standorte<\/strong>.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"3794\" data-end=\"3841\">Ein weiterer wichtiger Punkt laut Herrn Takada:<\/p>\n<blockquote data-start=\"3843\" data-end=\"4070\">\n<p data-start=\"3845\" data-end=\"4070\">\u201eDie <strong data-start=\"3850\" data-end=\"3893\">verl\u00e4ssliche Verf\u00fcgbarkeit der Produkte<\/strong> und das <strong data-start=\"3902\" data-end=\"3923\">faire Preisniveau<\/strong> von NETGEAR waren entscheidend daf\u00fcr, dass wir die Herausforderungen der Lieferkette w\u00e4hrend der globalen Chipkrise erfolgreich meistern konnten.\u201c<\/p>\n<\/blockquote>\n<p data-start=\"3845\" data-end=\"4070\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.netgear.com\/hub\/wp-content\/uploads\/2025\/09\/one.jpg\" alt=\"\" \/><\/p>\n    <\/div>\n        <div id=\"topic6\" class=\"skip-item\">\n                        <h2>Fazit<\/h2>\n                <p>Dank NETGEAR verf\u00fcgt <strong data-start=\"4115\" data-end=\"4135\">Higashi Holdings<\/strong> nun \u00fcber ein <strong data-start=\"4149\" data-end=\"4213\">leistungsf\u00e4higes, skalierbares und zukunftssicheres Netzwerk<\/strong>, das <strong data-start=\"4219\" data-end=\"4243\">einfach zu verwalten<\/strong> ist und die <strong data-start=\"4256\" data-end=\"4297\">weitere Expansion und Digitalisierung<\/strong> des Unternehmens zuverl\u00e4ssig unterst\u00fctzt.<\/p>\n    <\/div>\n        <div id=\"topic7\" class=\"skip-item\">\n                        <h2>Mehr Informationen<\/h2>\n                <p>\n<!-- IT NETGEAR BUSINESS-L\u00d6SUNGEN--><br \/>\nMehr \u00fcber unsere Business-Produkte erfahren<\/p>\n<div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-242892643058\" style=\"max-width:100%;max-height:100%;width:290px;height:50.390625px\" data-hubspot-wrapper-cta-id=\"242892643058\"><br \/>\n  <a href=\"https:\/\/cta-na2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLKSM9WTTg7%2FAeRV5qugDCzPgQ8MwIY0MWnrXLIcw1araTPlipAsbwW69SXPDIx4zCiH7IZWeqt%2BemeJLODhF%2FDlADckUBODpWmfLAeC%2B10Ud4YKVbb7l5mPLqwZdwx6VwqQcDHRL6LCGiyEcIh1qQqL0T3sxlnvr0t4bAvKCKjkKFXgqcVzXA%3D%3D&amp;webInteractiveContentId=242892643058&amp;portalId=242128791\" target=\"_blank\" rel=\"noopener\"><br \/>\n    <img decoding=\"async\" alt=\"NETGEAR BUSINESS-L\u00d6SUNGEN\" loading=\"lazy\" src=\"https:\/\/hubspot-no-cache-na2-prod.s3.amazonaws.com\/cta\/default\/242128791\/interactive-242892643058.png\" style=\"height: 100%;width: 100%;object-fit: fill\" \/><br \/>\n  <\/a>\n<\/div>\n<\/p>\n<p>\n<!-- IT ACADEMY --><br \/>\n Alles \u00fcber IP-Netzwerke lernen \u2013 in der NETGEAR ACADEMY<\/p>\n<div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-242204954356\" style=\"max-width:100%;max-height:100%;width:260px;height:50.390625px\" data-hubspot-wrapper-cta-id=\"242204954356\"><br \/>\n  <a href=\"https:\/\/cta-na2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLLkH9zel89o4qb5Zt0HNH2fd%2FRPXNoIMgiMzse7LTSjZhAi9JGmYnyHR1fYgVtqiIdLJk0UNBiYKxNP%2B%2FkdsBG1bikxBOFgBdX7C8VIedE8pHvRDgz%2F5zbzhiRhRBSaQNkZPdEPlmtk1BrN3KAJybsrZkfDr26KvP5h8b3eKmfGBpfusntV9159BNLCOue6HmfkXhcXHdUr6kvupL%2BZSl13fw11hQ%3D%3D&amp;webInteractiveContentId=242204954356&amp;portalId=242128791\" target=\"_blank\" rel=\"noopener\"><br \/>\n    <img decoding=\"async\" alt=\"NETGEAR ACADEMY\" loading=\"lazy\" src=\"https:\/\/hubspot-no-cache-na2-prod.s3.amazonaws.com\/cta\/default\/242128791\/interactive-242204954356.png\" style=\"height: 100%;width: 100%;object-fit: fill\" \/><br \/>\n  <\/a>\n<\/div>\n<\/p>\n<p>\n<!-- KONTAKT PRO-IT-TEAM --><br \/>\n Unsere Ingenieure unterst\u00fctzen Sie kostenlos bei Ihrem Projekt<\/p>\n<div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-245601739512\" style=\"max-width:100%;max-height:100%;width:230px;height:50.390625px\" data-hubspot-wrapper-cta-id=\"245601739512\"><br \/>\n  <a href=\"https:\/\/cta-na2.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLJr11uo8X2nE1LSD6Xjyr2Y4qHnMBiuTjepc%2Bu21JUc7ZZdAG7jEsrURlBKJ6f0gXIV8yzULoIPrEgSbXIfpubEaDTPtU2vi7JTsOLryr06L8dJPrqyt%2F2eKloPwOKZGDfL9zTAajC1ulDGRS7faQbDW8hv2qOUvg1kmKNy515wshiC%2FWSKAezkM0ul1Fbw9ZFaKkqGQny0qCHfNGg6IBozCtGRUg%3D%3D&amp;webInteractiveContentId=245601739512&amp;portalId=242128791\" target=\"_blank\" rel=\"noopener\"><br \/>\n    <img decoding=\"async\" alt=\"KONTAKT PRO-IT-TEAM\" loading=\"lazy\" src=\"https:\/\/hubspot-no-cache-na2-prod.s3.amazonaws.com\/cta\/default\/242128791\/interactive-245601739512.png\" style=\"height: 100%;width: 100%;object-fit: fill\" \/><br \/>\n  <\/a>\n<\/div>\n<\/p>\n<p style=\"margin-top: 50px\">\n<iframe loading=\"lazy\" src=\"https:\/\/405nrr.share-na2.hsforms.com\/25w_D-U5iS-e5KaSaP86jnQ\" width=\"100%\" height=\"1200px\"><\/iframe><\/p>\n    <\/div>\n    \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":94,"featured_media":10923,"parent":10318,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/blog-wifi.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10922","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Higashi Holdings entscheidet sich f\u00fcr NETGEAR - NETGEAR Hub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Higashi Holdings entscheidet sich f\u00fcr NETGEAR - NETGEAR Hub\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/\" \/>\n<meta property=\"og:site_name\" content=\"NETGEAR Hub\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NetgearAU\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T16:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dehub.netgear.com\/de\/hub\/wp-content\/uploads\/2025\/10\/Vignette-Higashi-383x288-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"383\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NETGEAR\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/case-studies\\\/it-case-studies\\\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\\\/\",\"url\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/case-studies\\\/it-case-studies\\\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\\\/\",\"name\":\"Higashi Holdings entscheidet sich f\u00fcr NETGEAR - NETGEAR Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/case-studies\\\/it-case-studies\\\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/case-studies\\\/it-case-studies\\\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Vignette-Higashi-383x288-1.jpg\",\"datePublished\":\"2025-10-16T08:38:51+00:00\",\"dateModified\":\"2025-11-25T16:00:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/case-studies\\\/it-case-studies\\\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/case-studies\\\/it-case-studies\\\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/case-studies\\\/it-case-studies\\\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Vignette-Higashi-383x288-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Vignette-Higashi-383x288-1.jpg\",\"width\":383,\"height\":288},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/case-studies\\\/it-case-studies\\\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business Articles Hub\",\"item\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"All Case Studies &#8211; DE\",\"item\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/case-studies\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"IT-Fallstudien\",\"item\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/business\\\/case-studies\\\/it-case-studies\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Higashi Holdings entscheidet sich f\u00fcr NETGEAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/#website\",\"url\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/\",\"name\":\"NETGEAR\",\"description\":\"Erkunden Sie unsere Hub-Seiten und st\u00f6bern Sie in Artikeln, um mehr \u00fcber NETGEAR Produkte und Technologien zu erfahren.\",\"publisher\":{\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/#organization\",\"name\":\"NETGEAR\",\"url\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dehub.netgear.com\\\/de\\\/hub\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/NETGEAR_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.dehub.netgear.com\\\/de\\\/hub\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/NETGEAR_logo.jpg\",\"width\":1500,\"height\":501,\"caption\":\"NETGEAR\"},\"image\":{\"@id\":\"https:\\\/\\\/dehub.netgear.com\\\/de\\\/hub\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NetgearAU\\\/\",\"https:\\\/\\\/x.com\\\/NETGEAR\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/netgear\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Higashi Holdings entscheidet sich f\u00fcr NETGEAR - NETGEAR Hub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/","og_locale":"de_DE","og_type":"article","og_title":"Higashi Holdings entscheidet sich f\u00fcr NETGEAR - NETGEAR Hub","og_url":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/","og_site_name":"NETGEAR Hub","article_publisher":"https:\/\/www.facebook.com\/NetgearAU\/","article_modified_time":"2025-11-25T16:00:20+00:00","og_image":[{"width":383,"height":288,"url":"https:\/\/dehub.netgear.com\/de\/hub\/wp-content\/uploads\/2025\/10\/Vignette-Higashi-383x288-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@NETGEAR","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/","url":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/","name":"Higashi Holdings entscheidet sich f\u00fcr NETGEAR - NETGEAR Hub","isPartOf":{"@id":"https:\/\/dehub.netgear.com\/de\/hub\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/#primaryimage"},"image":{"@id":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/#primaryimage"},"thumbnailUrl":"https:\/\/dehub.netgear.com\/de\/hub\/wp-content\/uploads\/2025\/10\/Vignette-Higashi-383x288-1.jpg","datePublished":"2025-10-16T08:38:51+00:00","dateModified":"2025-11-25T16:00:20+00:00","breadcrumb":{"@id":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/#primaryimage","url":"https:\/\/dehub.netgear.com\/de\/hub\/wp-content\/uploads\/2025\/10\/Vignette-Higashi-383x288-1.jpg","contentUrl":"https:\/\/dehub.netgear.com\/de\/hub\/wp-content\/uploads\/2025\/10\/Vignette-Higashi-383x288-1.jpg","width":383,"height":288},{"@type":"BreadcrumbList","@id":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/higashi-holdings-choosing-netgear-to-support-business-continuity-and-growth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dehub.netgear.com\/de\/hub\/"},{"@type":"ListItem","position":2,"name":"Business Articles Hub","item":"https:\/\/dehub.netgear.com\/de\/hub\/business\/"},{"@type":"ListItem","position":3,"name":"All Case Studies &#8211; DE","item":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/"},{"@type":"ListItem","position":4,"name":"IT-Fallstudien","item":"https:\/\/dehub.netgear.com\/de\/hub\/business\/case-studies\/it-case-studies\/"},{"@type":"ListItem","position":5,"name":"Higashi Holdings entscheidet sich f\u00fcr NETGEAR"}]},{"@type":"WebSite","@id":"https:\/\/dehub.netgear.com\/de\/hub\/#website","url":"https:\/\/dehub.netgear.com\/de\/hub\/","name":"NETGEAR","description":"Erkunden Sie unsere Hub-Seiten und st\u00f6bern Sie in Artikeln, um mehr \u00fcber NETGEAR Produkte und Technologien zu erfahren.","publisher":{"@id":"https:\/\/dehub.netgear.com\/de\/hub\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dehub.netgear.com\/de\/hub\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dehub.netgear.com\/de\/hub\/#organization","name":"NETGEAR","url":"https:\/\/dehub.netgear.com\/de\/hub\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dehub.netgear.com\/de\/hub\/#\/schema\/logo\/image\/","url":"https:\/\/www.dehub.netgear.com\/de\/hub\/wp-content\/uploads\/2019\/07\/NETGEAR_logo.jpg","contentUrl":"https:\/\/www.dehub.netgear.com\/de\/hub\/wp-content\/uploads\/2019\/07\/NETGEAR_logo.jpg","width":1500,"height":501,"caption":"NETGEAR"},"image":{"@id":"https:\/\/dehub.netgear.com\/de\/hub\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NetgearAU\/","https:\/\/x.com\/NETGEAR","https:\/\/www.linkedin.com\/company\/netgear"]}]}},"_links":{"self":[{"href":"https:\/\/dehub.netgear.com\/de\/hub\/wp-json\/wp\/v2\/pages\/10922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dehub.netgear.com\/de\/hub\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dehub.netgear.com\/de\/hub\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dehub.netgear.com\/de\/hub\/wp-json\/wp\/v2\/users\/94"}],"replies":[{"embeddable":true,"href":"https:\/\/dehub.netgear.com\/de\/hub\/wp-json\/wp\/v2\/comments?post=10922"}],"version-history":[{"count":3,"href":"https:\/\/dehub.netgear.com\/de\/hub\/wp-json\/wp\/v2\/pages\/10922\/revisions"}],"predecessor-version":[{"id":11055,"href":"https:\/\/dehub.netgear.com\/de\/hub\/wp-json\/wp\/v2\/pages\/10922\/revisions\/11055"}],"up":[{"embeddable":true,"href":"https:\/\/dehub.netgear.com\/de\/hub\/wp-json\/wp\/v2\/pages\/10318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dehub.netgear.com\/de\/hub\/wp-json\/wp\/v2\/media\/10923"}],"wp:attachment":[{"href":"https:\/\/dehub.netgear.com\/de\/hub\/wp-json\/wp\/v2\/media?parent=10922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}